{"id":12123,"date":"2025-10-02T01:09:24","date_gmt":"2025-10-02T05:09:24","guid":{"rendered":"https:\/\/www.perryschools.org\/he\/event\/winter-musical-rehearsal-24\/"},"modified":"2025-12-11T03:24:07","modified_gmt":"2025-12-11T08:24:07","slug":"winter-musical-rehearsal-24","status":"publish","type":"tribe_events","link":"https:\/\/www.perryschools.org\/he\/event\/winter-musical-rehearsal-24\/","title":{"rendered":"Winter Musical Rehearsal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-12123","tribe_events","type-tribe_events","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Winter Musical Rehearsal - Homecroft Elementary<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.perryschools.org\/he\/event\/winter-musical-rehearsal-24\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Winter Musical Rehearsal - Homecroft Elementary\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.perryschools.org\/he\/event\/winter-musical-rehearsal-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Homecroft Elementary\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-11T08:24:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.perryschools.org\\\/he\\\/event\\\/winter-musical-rehearsal-24\\\/\",\"url\":\"https:\\\/\\\/www.perryschools.org\\\/he\\\/event\\\/winter-musical-rehearsal-24\\\/\",\"name\":\"Winter Musical Rehearsal - Homecroft Elementary\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.perryschools.org\\\/he\\\/#website\"},\"datePublished\":\"2025-10-02T05:09:24+00:00\",\"dateModified\":\"2025-12-11T08:24:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.perryschools.org\\\/he\\\/event\\\/winter-musical-rehearsal-24\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.perryschools.org\\\/he\\\/event\\\/winter-musical-rehearsal-24\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.perryschools.org\\\/he\\\/event\\\/winter-musical-rehearsal-24\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.perryschools.org\\\/he\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.perryschools.org\\\/he\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Winter Musical Rehearsal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.perryschools.org\\\/he\\\/#website\",\"url\":\"https:\\\/\\\/www.perryschools.org\\\/he\\\/\",\"name\":\"Homecroft Elementary\",\"description\":\"Hornet Pride\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.perryschools.org\\\/he\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Winter Musical Rehearsal - Homecroft Elementary","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.perryschools.org\/he\/event\/winter-musical-rehearsal-24\/","og_locale":"en_US","og_type":"article","og_title":"Winter Musical Rehearsal - Homecroft Elementary","og_url":"https:\/\/www.perryschools.org\/he\/event\/winter-musical-rehearsal-24\/","og_site_name":"Homecroft Elementary","article_modified_time":"2025-12-11T08:24:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.perryschools.org\/he\/event\/winter-musical-rehearsal-24\/","url":"https:\/\/www.perryschools.org\/he\/event\/winter-musical-rehearsal-24\/","name":"Winter Musical Rehearsal - Homecroft Elementary","isPartOf":{"@id":"https:\/\/www.perryschools.org\/he\/#website"},"datePublished":"2025-10-02T05:09:24+00:00","dateModified":"2025-12-11T08:24:07+00:00","breadcrumb":{"@id":"https:\/\/www.perryschools.org\/he\/event\/winter-musical-rehearsal-24\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.perryschools.org\/he\/event\/winter-musical-rehearsal-24\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.perryschools.org\/he\/event\/winter-musical-rehearsal-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.perryschools.org\/he\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.perryschools.org\/he\/events\/"},{"@type":"ListItem","position":3,"name":"Winter Musical Rehearsal"}]},{"@type":"WebSite","@id":"https:\/\/www.perryschools.org\/he\/#website","url":"https:\/\/www.perryschools.org\/he\/","name":"Homecroft Elementary","description":"Hornet Pride","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.perryschools.org\/he\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.perryschools.org\/he\/wp-json\/wp\/v2\/tribe_events\/12123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.perryschools.org\/he\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.perryschools.org\/he\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.perryschools.org\/he\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.perryschools.org\/he\/wp-json\/wp\/v2\/tribe_events\/12123\/revisions"}],"predecessor-version":[{"id":12137,"href":"https:\/\/www.perryschools.org\/he\/wp-json\/wp\/v2\/tribe_events\/12123\/revisions\/12137"}],"wp:attachment":[{"href":"https:\/\/www.perryschools.org\/he\/wp-json\/wp\/v2\/media?parent=12123"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.perryschools.org\/he\/wp-json\/wp\/v2\/tags?post=12123"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.perryschools.org\/he\/wp-json\/wp\/v2\/tribe_events_cat?post=12123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}